{"id":1014,"date":"2014-09-07T22:06:41","date_gmt":"2014-09-07T20:06:41","guid":{"rendered":"http:\/\/madcham.com\/wordpress\/?p=1014"},"modified":"2020-05-13T21:54:53","modified_gmt":"2020-05-13T19:54:53","slug":"vergesellschaftung","status":"publish","type":"post","link":"https:\/\/www.madcham.de\/de\/vergesellschaftung\/","title":{"rendered":"Vergesellschaftung"},"content":{"rendered":"<h4 style=\"text-align: justify;\">Cham\u00e4leons untereinander<\/h4>\n<p style=\"text-align: justify;\">Die meisten Cham\u00e4leons, z.B. <em>Furcifer pardalis<\/em>, k\u00f6nnen nur einzeln gehalten werden, da sie innerartlich sehr aggressiv sind. Paarhaltungen sind oft nur f\u00fcr die Dauer der Paarung selbst m\u00f6glich. Die Cham\u00e4leons m\u00fcssen sich dabei nicht unbedingt <a href=\"https:\/\/www.madcham.de\/de\/abwehr-flucht-verhalten-baumbewohner\/\">bei\u00dfen<\/a> oder angreifen, allein die Anwesenheit eines zweiten Tieres kann durch den ausgel\u00f6sten Stress beim unterdr\u00fcckten Tier bis zum Tod f\u00fchren. Jungtiere k\u00f6nnen oft noch in Gruppen aufgezogen werden, bereits im Alter von wenigen Monaten muss man die Cham\u00e4leons jedoch schon einzeln unterbringen.<\/p>\n<p style=\"text-align: justify;\">Bei einigen afrikanischen Cham\u00e4leonarten sind Paar- oder Gruppenhaltungen bei gro\u00dfz\u00fcgigem Platzangebot unter Umst\u00e4nden m\u00f6glich. In solchen F\u00e4llen sollten stets Ausweichterrarien zur Verf\u00fcgung stellen, denn nicht jedes Individuum kommt mit Partnertieren zurecht. Auch einzelne Paarhaltungen von <em>Calumma parsonii<\/em> sind bekannt. Solche Gruppenhaltungen sollten ausschlie\u00dflich von erfahrenen Haltern versucht werden, die die Individuen seit Jahren kennen und auch kleine Anzeichen von Unvertr\u00e4glichkeiten bemerken. Bei Paarhaltungen von Jungtier an kann es vorkommen, dass M\u00e4nnchen sich nicht verpaaren oder Weibchen viel zu fr\u00fch tr\u00e4chtig werden. Im Zweifelsfall ist die Einzelhaltung immer die sichere Variante.<\/p>\n<h4 style=\"text-align: justify;\">Vergesellschaften von Cham\u00e4leons mit anderen Reptilien<\/h4>\n<p style=\"text-align: justify;\">Vielfach m\u00f6chten Cham\u00e4leonhalter (vor allem Anf\u00e4nger) noch andere Arten im gleichen Terrarium pflegen. Damit spart man Platz, Technik (und damit Geld) und die Tiere k\u00f6nnen miteinander interagieren, anstatt gelangweilt herumzusitzen\u2026oder ist es vielleicht doch nicht so einfach?<\/p>\n<p style=\"text-align: justify;\">Grunds\u00e4tzlich sollten folgende \u00dcberlegungen gemacht werden:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Die zu vergesellschaftenden Arten sollten aus dem gleichen Lebensraum stammen und in der Natur parallel vorkommen. Zus\u00e4tzlich sollten sie gleiche klimatische Bedingungen ben\u00f6tigen und sehr \u00e4hnliche Terrarieneinrichtung. Ein Schmuckhornfrosch z.B. ben\u00f6tigt andere Bedingungen als ein Cham\u00e4leon und stammt aus S\u00fcdamerika, wo es \u00fcberhaupt keine Cham\u00e4leons gibt.<\/li>\n<li>Eine Art sollte keine Beute bzw. <a href=\"https:\/\/www.madcham.de\/de\/fressfeinde-von-chamaeleons-auf-madagaskar\/\">Fressfeind<\/a> der anderen sein. Gro\u00dfe Cham\u00e4leons versuchen auf fast alles zu schie\u00dfen, was sich schnell bewegt. Kleine Geckos, Anolis, Fr\u00f6sche, Kleins\u00e4uger oder <a href=\"https:\/\/www.madcham.de\/de\/fressfeinde-von-chamaeleons-auf-madagaskar\/\">V\u00f6gel<\/a> im gleichen Terrarium\/Raum sind daher willkommenes <a href=\"https:\/\/www.madcham.de\/de\/chamaeleonfutter\/\">Futter<\/a>. Vorsicht auch bei gr\u00f6\u00dferen Geckoarten wie <em>Phelsuma grandis<\/em> &#8211; auch von diesen sind Angriffe von Cham\u00e4leons ausgehend bekannt. Andersherum k\u00f6nnen auch gr\u00f6\u00dfere Echsen kleine Cham\u00e4leons problemlos verspeisen.<\/li>\n<li>Die Tiere sollten sich gegenseitig nicht st\u00f6ren. Eine nachtaktive, gro\u00dfe Geckoart z.B. kann ein schlafendes Cham\u00e4leon massiv st\u00f6ren und andersherum am Tag.<\/li>\n<li>Normale Terrariengr\u00f6\u00dfen reichen nicht aus. Es muss ein sehr gro\u00dfz\u00fcgiges, f\u00fcr beide Arten mehr als ausreichend Platz bietendes, sehr gut strukturiertes Terrarium vorhanden sein.<\/li>\n<li>F\u00fcr alle Tiere, die in ein fremdes Becken dazugesetzt werden, m\u00fcssen Ausweichterrarien zur Verf\u00fcgung stehen. Das hei\u00dft konkret, dass f\u00fcr jedes Tier ein nicht besetztes, aber voll eingerichtetes Terrarium zus\u00e4tzlich vorhanden sein muss. An Technik, Platz und Geld spart man also nichts.<\/li>\n<li>Der Halter sollte beide Arten getrennt voneinander seit Jahren erfolgreich pflegen, gut einsch\u00e4tzen k\u00f6nnen und die Einzeltiere und ihr Verhalten kennen. Neu gekaufte Tiere einfach zusammenzustecken birgt ein hohes Konfliktrisiko. Zudem sollten gerade Anf\u00e4nger in der Cham\u00e4leonhaltung zuerst lernen, die Tiere und ihre oft leicht zu \u00fcbersehenden Anzeichen f\u00fcr Erkrankungen, Stimmung usw. richtig zu deuten. Keine Quarant\u00e4ne durchzuf\u00fchren kann au\u00dferdem bei Parasitenbefall das Ausr\u00e4umen des kompletten Terrariums bedeuten.<\/li>\n<li>Der Halter muss Zeit haben, die Tiere insbesondere w\u00e4hrend der ersten Wochen intensiv zu beobachten, um gegebenenfalls Einzeltiere wieder von den anderen zu trennen.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Vergesellschaftungen k\u00f6nnen nur funktionieren, wenn beide Arten nicht wegen der \u201eNachbarn\u201c zur\u00fcckstecken m\u00fcssen. Wie man an den genannten Bedingungen sieht, erfordert eine dauerhaft funktionierende Vergesellschaftung verschiedener Arten immense Vorbereitungen und relativ hohen Aufwand. Demgegen\u00fcber stehen zwar eine Umweltbereicherung beider Arten und f\u00fcr den Halter tolle Beobachtungen, jedoch auch vermehrt Stress und eine erh\u00f6hte Verletzungsgefahr f\u00fcr die Bewohner.<\/p>\n<p style=\"text-align: justify;\">Viele Zoos zeigen Terrarien mit unterschiedlichen, vergesellschafteten Arten. Daraus zu schlie\u00dfen, man k\u00f6nne die gleichen Arten zu Hause genauso gut gemeinsam unterbringen, kann fatale Folgen haben. Zoos haben andere Bedingungen als Privathalter, haben in der Regel mehr Ressourcen f\u00fcr kurzfristige Unterbringung und \u00fcber Jahrzehnte erfahrene Pfleger. Manche zoologischen Einrichtungen zeigen trotz besserem Wissen fragw\u00fcrdige Vergesellschaftungen. Ob und wie lange diese funktionieren, bleibt dem Besucher verborgen.<\/p>\n<p style=\"text-align: justify;\"><strong>Grunds\u00e4tzlich gilt: Vergesellschaftungen sollten sehr erfahrenen Haltern vorbehalten bleiben<\/strong> und funktionieren langfristig nur unter speziellen Bedingungen. Au\u00dferdem immer daran denken: Was beim einen Halter gut geht, muss es deshalb noch lange nicht beim n\u00e4chsten. Wir empfehlen Vergesellschaftungen grunds\u00e4tzlich nicht, sondern raten ausdr\u00fccklich davon ab.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cham\u00e4leons untereinander Die meisten Cham\u00e4leons, z.B. Furcifer pardalis, k\u00f6nnen nur einzeln gehalten werden, da sie innerartlich sehr aggressiv sind. Paarhaltungen sind oft nur f\u00fcr die Dauer der Paarung selbst m\u00f6glich. Die Cham\u00e4leons m\u00fcssen sich dabei nicht unbedingt bei\u00dfen oder angreifen, allein die Anwesenheit eines zweiten Tieres kann durch den ausgel\u00f6sten Stress beim unterdr\u00fcckten Tier bis zum Tod f\u00fchren. Jungtiere k\u00f6nnen oft noch in Gruppen aufgezogen werden, bereits im Alter von wenigen Monaten muss man die Cham\u00e4leons jedoch schon einzeln unterbringen. Bei einigen afrikanischen Cham\u00e4leonarten sind Paar- oder Gruppenhaltungen bei gro\u00dfz\u00fcgigem Platzangebot unter Umst\u00e4nden m\u00f6glich. In solchen F\u00e4llen sollten stets Ausweichterrarien zur Verf\u00fcgung stellen, denn nicht jedes Individuum kommt mit Partnertieren zurecht. Auch einzelne Paarhaltungen von Calumma parsonii sind bekannt. Solche Gruppenhaltungen sollten ausschlie\u00dflich von erfahrenen Haltern versucht werden, die die Individuen seit Jahren kennen und auch kleine Anzeichen von Unvertr\u00e4glichkeiten bemerken. Bei Paarhaltungen von Jungtier an kann es vorkommen, dass M\u00e4nnchen sich nicht verpaaren oder Weibchen viel zu fr\u00fch tr\u00e4chtig werden. Im Zweifelsfall ist die Einzelhaltung immer die sichere Variante. Vergesellschaften von Cham\u00e4leons mit anderen Reptilien Vielfach m\u00f6chten Cham\u00e4leonhalter (vor allem Anf\u00e4nger) noch andere Arten im gleichen Terrarium pflegen. Damit spart man Platz, Technik (und damit Geld) und die Tiere&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1135,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[40],"tags":[998,995,991,992,997,50,999,49,994,993,1002,1001,1000,990,996,1003],"_links":{"self":[{"href":"https:\/\/www.madcham.de\/de\/wp-json\/wp\/v2\/posts\/1014"}],"collection":[{"href":"https:\/\/www.madcham.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madcham.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madcham.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madcham.de\/de\/wp-json\/wp\/v2\/comments?post=1014"}],"version-history":[{"count":13,"href":"https:\/\/www.madcham.de\/de\/wp-json\/wp\/v2\/posts\/1014\/revisions"}],"predecessor-version":[{"id":9381,"href":"https:\/\/www.madcham.de\/de\/wp-json\/wp\/v2\/posts\/1014\/revisions\/9381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.madcham.de\/de\/wp-json\/wp\/v2\/media\/1135"}],"wp:attachment":[{"href":"https:\/\/www.madcham.de\/de\/wp-json\/wp\/v2\/media?parent=1014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madcham.de\/de\/wp-json\/wp\/v2\/categories?post=1014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madcham.de\/de\/wp-json\/wp\/v2\/tags?post=1014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}