{"id":7444,"date":"2017-06-20T20:39:40","date_gmt":"2017-06-20T18:39:40","guid":{"rendered":"https:\/\/www.madcham.de\/?p=7444"},"modified":"2025-02-14T13:28:45","modified_gmt":"2025-02-14T12:28:45","slug":"der-farbwechsel","status":"publish","type":"post","link":"https:\/\/www.madcham.de\/fr\/der-farbwechsel\/","title":{"rendered":"Le changement de couleur"},"content":{"rendered":"<p class=\"dropcap\" style=\"text-align: justify;\">La premi\u00e8re chose que la plupart des gens pensent d&rsquo;un cam\u00e9l\u00e9on est g\u00e9n\u00e9ralement le fait que ces animaux peuvent changer la couleur de leur peau. Cet article va au fond de la question de savoir comment fonctionne ce changement de couleur et \u00e0 quoi il sert r\u00e9ellement.<\/p>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: justify;\">Comment fonctionne le changement de couleur du cam\u00e9l\u00e9on ?<\/h4>\n<p style=\"text-align: justify;\">Les chromatophores, cellules optiques sp\u00e9cialis\u00e9es de la peau, sont responsables du changement de couleur. Ils sont situ\u00e9s sous la couche de peau la plus externe (\u00e9piderme) du derme, en couches superpos\u00e9es. Les m\u00e9lanophores sont responsables des couleurs bleu fonc\u00e9 et noir, les xanthophores des pigments jaunes et oranges, les \u00e9rythrophores des pigments rouges et les guanophores des pigments brillants argent\u00e9s. Chez les cam\u00e9l\u00e9ons, il y a aussi des cellules qui n&rsquo;ont pas du tout besoin de pigments pour que la peau apparaisse de couleur diff\u00e9rente. Ils effectuent le changement de couleur par r\u00e9flexion.<\/p>\n<div id=\"attachment_7449\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Guanine-crystals.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7449\" class=\"wp-image-7449 size-medium\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Guanine-crystals-300x268.jpg\" alt=\"\" width=\"300\" height=\"268\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Guanine-crystals-300x268.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Guanine-crystals-81x72.jpg 81w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Guanine-crystals.jpg 337w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-7449\" class=\"wp-caption-text\">Cristaux de guanine dans la couche des S-iridophores (S-irid. et d) et dans la couche des D-iridophores (D-irid. et e) sous l&rsquo;\u00e9piderme (ep), repr\u00e9sent\u00e9s \u00e0 gauche dans une coupe de tissu et \u00e0 droite sous le microscope \u00e9lectronique \u00e0 transmission. A d, on peut voir \u00e0 quel point les cristaux de guanine sont dispos\u00e9s diff\u00e9remment dans deux couleurs de peau diff\u00e9rentes. Graphique de la publication \u00ab\u00a0Photonic crytals cause active color change in chameleons\u00a0\u00bb von Teyssier et al. 2014, lizensiert unter Creative Commons BY 4.0.<\/p><\/div>\n<p style=\"text-align: justify;\">Une distinction est faite entre une couche sup\u00e9rieure (en anglais <em><strong>s<\/strong>uperifical<\/em>) d&rsquo;iridophores S et une couche inf\u00e9rieure (en anglais <em><strong>d<\/strong>eep<\/em>) d&rsquo;iridophores D. Les iridophores contiennent des cristaux de guanine, qui sont la cl\u00e9 du changement de couleur des cam\u00e9l\u00e9ons.<\/p>\n<p style=\"text-align: justify;\">Dans la couche sup\u00e9rieure des S-iridophores, les cristaux de guanine sont tr\u00e8s proches les uns des autres et sont dispos\u00e9s en petits triangles. Les cristaux de guanine peuvent modifier leur distance les uns par rapport aux autres. Ils fonctionnent comme un cristal photonique qui peut influencer le mouvement des photons (particules de lumi\u00e8re) et ainsi modifier la r\u00e9flexion de la couleur de la lumi\u00e8re tombant sur la peau. Les S-iridophores sont responsables du fait que la peau du cam\u00e9l\u00e9on peut changer de couleur, passant du vert au jaune ou \u00e0 l&rsquo;orange.<\/p>\n<p style=\"text-align: justify;\">Dans la couche inf\u00e9rieure D-iridophore de la peau du cam\u00e9l\u00e9on, les cristaux de guanine ont la forme de petites briques et sont dispos\u00e9s de fa\u00e7on assez d\u00e9sordonn\u00e9e les uns \u00e0 c\u00f4t\u00e9 des autres. Cette couche fournit la r\u00e9flexion dans une gamme proche de l&rsquo;infrarouge, ce qui entra\u00eene une absorption plus faible de la lumi\u00e8re solaire. Il sert presque au cam\u00e9l\u00e9on de protection contre la chaleur naturellement int\u00e9gr\u00e9e.<\/p>\n<p style=\"text-align: justify;\">Chez les cam\u00e9l\u00e9ons de couleur rouge, une grande partie des iridophores de la peau est remplac\u00e9e par des \u00e9rythrophores. La peau de cam\u00e9l\u00e9on rouge ne peut pas changer de couleur, mais peut varier entre le rouge fonc\u00e9 et le rouge vif. La peau bleue du cam\u00e9l\u00e9on, par contre, peut non seulement devenir plus claire, mais m\u00eame blanche.<\/p>\n<p style=\"text-align: justify;\">La couche sup\u00e9rieure des S-iridophores n&rsquo;est compl\u00e8tement pr\u00e9sente que chez les cam\u00e9l\u00e9ons adultes, ce qui explique pourquoi les jeunes animaux ne produisent pas encore la pleine coloration de leurs cong\u00e9n\u00e8res plus \u00e2g\u00e9s. Ils n&rsquo;ont que la couche de D-iridophores dans leur peau et n&rsquo;ont pas encore compl\u00e8tement d\u00e9velopp\u00e9 les S-iridophores.<\/p>\n<p style=\"text-align: justify;\">La structure de la peau du cam\u00e9l\u00e9on dans les couches d&rsquo;iridophores et la fonction des cristaux de guanine n&rsquo;ont \u00e9t\u00e9 d\u00e9crites qu&rsquo;en 2014. Auparavant, on pensait que le changement de couleur \u00e9tait exclusivement caus\u00e9 par la diff\u00e9rence de r\u00e9partition des pigments de couleur. En fait, la dispersion et l&rsquo;agr\u00e9gation des pigments sont responsables de l&rsquo;expression de couleurs plus claires et plus sombres. Cependant, cette id\u00e9e ne pourrait pas expliquer de mani\u00e8re satisfaisante pourquoi les cam\u00e9l\u00e9ons peuvent changer de couleur en quelques secondes. Les cristaux de guanine peuvent le faire &#8211; ils produisent des couleurs dites structurelles qui ne sont pas caus\u00e9es par des pigments &#8211; ce qui, il y a quelques ann\u00e9es seulement, a permis de d\u00e9m\u00ealer une autre fonction du corps chez les cam\u00e9l\u00e9ons. La mani\u00e8re dont les cam\u00e9l\u00e9ons peuvent contr\u00f4ler les r\u00e9seaux de cristaux de guanine dans leur peau n&rsquo;a pas encore \u00e9t\u00e9 clarifi\u00e9e. Ce que l&rsquo;on sait d\u00e9j\u00e0, c&rsquo;est que chaque changement de couleur se produit de mani\u00e8re totalement inconsciente. Le cam\u00e9l\u00e9on ne peut donc pas cr\u00e9er des motifs au hasard dans sa peau.<\/p>\n<div id='gallery-7' class='gallery galleryid-7444 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2015\/06\/MG_0030-Gro\u00df.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"674\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2015\/06\/MG_0030-Gro\u00df-1024x674.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-7-2752\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2015\/06\/MG_0030-Gro\u00df-1024x674.jpg 1024w, https:\/\/www.madcham.de\/wp-content\/uploads\/2015\/06\/MG_0030-Gro\u00df-300x198.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2015\/06\/MG_0030-Gro\u00df-768x506.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2015\/06\/MG_0030-Gro\u00df-1171x771.jpg 1171w, https:\/\/www.madcham.de\/wp-content\/uploads\/2015\/06\/MG_0030-Gro\u00df-420x277.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2015\/06\/MG_0030-Gro\u00df-81x53.jpg 81w, https:\/\/www.madcham.de\/wp-content\/uploads\/2015\/06\/MG_0030-Gro\u00df.jpg 1640w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-7-2752'>\n\t\t\t\tNormalf\u00e4rbung bei Furcifer bifidus in Vohimana\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2016\/11\/Furcifer-bifidus-tr\u00e4chtig.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"948\" height=\"612\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2016\/11\/Furcifer-bifidus-tr\u00e4chtig.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-7-3625\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2016\/11\/Furcifer-bifidus-tr\u00e4chtig.jpg 948w, https:\/\/www.madcham.de\/wp-content\/uploads\/2016\/11\/Furcifer-bifidus-tr\u00e4chtig-300x194.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2016\/11\/Furcifer-bifidus-tr\u00e4chtig-768x496.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2016\/11\/Furcifer-bifidus-tr\u00e4chtig-420x271.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2016\/11\/Furcifer-bifidus-tr\u00e4chtig-81x52.jpg 81w\" sizes=\"(max-width: 948px) 100vw, 948px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-7-3625'>\n\t\t\t\tTr\u00e4chtigkeitsf\u00e4rbung bei Furcifer bifidus in Vohimana\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"611\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-7-7453\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis.jpg 1000w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis-300x183.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis-768x469.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis-420x257.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis-81x49.jpg 81w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-7-7453'>\n\t\t\t\tPanthercham\u00e4leon nahe Ambilobe in Ruhe\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis-2-e1528139191932.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"622\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis-2-e1528139191932.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-7-7452\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis-2-e1528139191932.jpg 1000w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis-2-e1528139191932-300x187.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis-2-e1528139191932-768x478.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis-2-e1528139191932-420x261.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambilobe-Furcifer-pardalis-2-e1528139191932-81x50.jpg 81w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-7-7452'>\n\t\t\t\tDas gleiche Panthercham\u00e4leon, nachdem es einen Konkurrenten gesichtet hat\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2017\/07\/Furcifer-balteatus-Weibchen-in-Ranomafana-2017-1-e1528140661804.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"878\" height=\"587\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2017\/07\/Furcifer-balteatus-Weibchen-in-Ranomafana-2017-1-e1528140661804.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-7-4290\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2017\/07\/Furcifer-balteatus-Weibchen-in-Ranomafana-2017-1-e1528140661804.jpg 878w, https:\/\/www.madcham.de\/wp-content\/uploads\/2017\/07\/Furcifer-balteatus-Weibchen-in-Ranomafana-2017-1-e1528140661804-300x201.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2017\/07\/Furcifer-balteatus-Weibchen-in-Ranomafana-2017-1-e1528140661804-768x513.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2017\/07\/Furcifer-balteatus-Weibchen-in-Ranomafana-2017-1-e1528140661804-420x281.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2017\/07\/Furcifer-balteatus-Weibchen-in-Ranomafana-2017-1-e1528140661804-81x54.jpg 81w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-7-4290'>\n\t\t\t\tTr\u00e4chtiges Furcifer balteatus Weibchen in Ruhef\u00e4rbung in Ranomafana\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2014\/09\/Furcifer-balteatus-tr\u00e4chtig.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"664\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2014\/09\/Furcifer-balteatus-tr\u00e4chtig.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2014\/09\/Furcifer-balteatus-tr\u00e4chtig.jpg 1000w, https:\/\/www.madcham.de\/wp-content\/uploads\/2014\/09\/Furcifer-balteatus-tr\u00e4chtig-300x199.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2014\/09\/Furcifer-balteatus-tr\u00e4chtig-768x510.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2014\/09\/Furcifer-balteatus-tr\u00e4chtig-420x279.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2014\/09\/Furcifer-balteatus-tr\u00e4chtig-81x54.jpg 81w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: justify;\">Quand un cam\u00e9l\u00e9on change-t-il de couleur ?<\/h4>\n<p style=\"text-align: justify;\">Autrefois, on pensait que le changement de couleur du cam\u00e9l\u00e9on servait \u00e0 mieux camoufler l&rsquo;animal. Aujourd&rsquo;hui, nous savons que ce n&rsquo;est pas le cas: le cam\u00e9l\u00e9on utilise ses changements de couleur de peau principalement pour communiquer. Les femelles qui sont pr\u00eates \u00e0 s&rsquo;accoupler, par exemple, pr\u00e9sentent g\u00e9n\u00e9ralement une coloration compl\u00e8tement diff\u00e9rente de celle des cam\u00e9l\u00e9ons enceintes, pour signaler \u00e0 leurs partenaires potentiels \u00ab\u00a0Tu n&rsquo;as plus aucune chance avec moi\u00a0\u00bb. Les m\u00e2les qui veulent impressionner leurs cong\u00e9n\u00e8res ou menacer quelqu&rsquo;un sont extr\u00eamement color\u00e9s et brillants. Un cam\u00e9l\u00e9on menac\u00e9 ou inf\u00e9rieur pr\u00e9sente g\u00e9n\u00e9ralement une coloration tr\u00e8s sombre \u00e0 noire &#8211; il est litt\u00e9ralement agac\u00e9 par le noir.<\/p>\n<p style=\"text-align: justify;\">Mais la couleur est aussi utilis\u00e9e de mani\u00e8re tr\u00e8s pratique : les cam\u00e9l\u00e9ons se colorent aussi plus fonc\u00e9s afin de pouvoir capter plus de lumi\u00e8re du soleil et donc de chaleur aux moments les plus frais de la journ\u00e9e. En revanche, pendant le sommeil, ils se refroidissent et deviennent tr\u00e8s l\u00e9gers. Les animaux malades sont souvent aussi de couleur p\u00e2le, mais m\u00eame les animaux en hibernation pr\u00e9sentent g\u00e9n\u00e9ralement des couleurs moins vives.<\/p>\n<div id='gallery-8' class='gallery galleryid-7444 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-farblos-e1528139970998.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-farblos-e1528139970998.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-8-7457\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-farblos-e1528139970998.jpg 1000w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-farblos-e1528139970998-300x200.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-farblos-e1528139970998-768x512.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-farblos-e1528139970998-420x280.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-farblos-e1528139970998-81x54.jpg 81w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-8-7457'>\n\t\t\t\tPanthercham\u00e4leon-M\u00e4nnchen, das sich in Anwesenheit eines anderen M\u00e4nnchens dunkel verf\u00e4rbt hat\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-bunt.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-bunt.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-8-7456\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-bunt.jpg 1000w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-bunt-300x200.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-bunt-768x512.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-bunt-420x280.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ambanja-Furcifer-pardalis-bunt-81x54.jpg 81w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-8-7456'>\n\t\t\t\tDer Kontrahent der gleichen Lokalform\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-adult.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"672\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-adult.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-8-7461\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-adult.jpg 1000w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-adult-300x202.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-adult-768x516.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-adult-420x282.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-adult-81x54.jpg 81w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-8-7461'>\n\t\t\t\tEin adultes Panthercham\u00e4leon in Ankify mit ausgepr\u00e4gten Farben\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-juvenil.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-juvenil.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-8-7462\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-juvenil.jpg 1000w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-juvenil-300x200.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-juvenil-768x512.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-juvenil-420x280.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Farbwechsel-Ankify-Furcifer-pardalis-juvenil-81x54.jpg 81w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-8-7462'>\n\t\t\t\tEin Jungtier der gleichen Lokalform\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<h4>Les cam\u00e9l\u00e9ons peuvent-ils s&rsquo;adapter \u00e0 la couleur de leur fond ?<\/h4>\n<p style=\"text-align: justify;\">Chaque type de cam\u00e9l\u00e9on n&rsquo;a toujours qu&rsquo;un spectre de couleurs tr\u00e8s sp\u00e9cifique. Les cam\u00e9l\u00e9ons ne peuvent donc pas changer de couleur \u00e0 volont\u00e9 ni m\u00eame s&rsquo;adapter \u00e0 leur milieu &#8211; c&rsquo;est un mythe qui circule toujours et que l&rsquo;on partage assid\u00fbment dans les m\u00e9dias sociaux, mais c&rsquo;est tout simplement faux. Les cam\u00e9l\u00e9ons ne peuvent varier leurs couleurs qu&rsquo;\u00e0 l&rsquo;int\u00e9rieur du spectre de couleurs sp\u00e9cifique \u00e0 l&rsquo;esp\u00e8ce et au sexe. Les petites cam\u00e9l\u00e9ons terrestre n&rsquo;ont qu&rsquo;un tr\u00e8s petit spectre de couleurs, du noir au brun en passant par les tons argileux, adapt\u00e9 \u00e0 leur habitat juste au-dessus du sol. La couleur sert donc ici non seulement \u00e0 la communication mais aussi au camouflage. D&rsquo;autres esp\u00e8ces ont des \u00e9chelles de couleurs tr\u00e8s larges allant du rouge vif au bleu, au vert, au jaune et au blanc comme les cam\u00e9l\u00e9ons panth\u00e8res qui vivent dans les arbres et les buissons.<\/p>\n<h4 style=\"text-align: justify;\">Fluorescence sous lumi\u00e8re UV<\/h4>\n<p style=\"text-align: justify;\">Les cam\u00e9l\u00e9ons ont des processus osseux et des peignes, en particulier dans la r\u00e9gion de la t\u00eate et du dos, qui ne sont presque couverts que par de fines \u00e9cailles. Dans ces endroits, la peau est particuli\u00e8rement fine par rapport \u00e0 celle du reste du corps, ils forment de v\u00e9ritables \u00ab\u00a0fen\u00eatres\u00a0\u00bb. On sait depuis longtemps que les os sont fluorescents sous la lumi\u00e8re <a href=\"https:\/\/www.madcham.de\/fr\/uv-b-strahlung\/\">UV<\/a>. Si tu tiens une lampe UV (\u00ab\u00a0lumi\u00e8re noire\u00a0\u00bb) au-dessus d&rsquo;un cam\u00e9l\u00e9on, les os fluorescents scintillent \u00e0 travers les endroits o\u00f9 la peau est tr\u00e8s fine. On suppose que les motifs bizarres qui se produisent sous la lumi\u00e8re UV, en particulier sur la t\u00eate, servent de moyen de communication intra-esp\u00e8ce, tout comme le changement de couleur. Les cam\u00e9l\u00e9ons peuvent probablement voir dans la gamme des ultraviolets et ainsi percevoir les motifs invisibles \u00e0 l&rsquo;\u0153il humain. Cela permettrait non seulement aux cam\u00e9l\u00e9ons de distinguer les diff\u00e9rentes esp\u00e8ces sur de longues distances, mais les femelles seraient \u00e9galement en mesure de reconna\u00eetre \u00e0 distance quels cam\u00e9l\u00e9ons sont particuli\u00e8rement adapt\u00e9s comme partenaires potentiels.<\/p>\n<div id='gallery-9' class='gallery galleryid-7444 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-ohne-UV-Licht.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-ohne-UV-Licht.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-9-7445\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-ohne-UV-Licht.jpg 1000w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-ohne-UV-Licht-300x200.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-ohne-UV-Licht-768x512.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-ohne-UV-Licht-420x280.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-ohne-UV-Licht-81x54.jpg 81w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-9-7445'>\n\t\t\t\tBrookesia antakarana im Montagne d&rsquo;Ambre im <a href=\"https:\/\/www.madcham.de\/fr\/terrarienbeleuchtung\/\">Licht<\/a> einer Taschenlampe\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-unter-UV-Licht.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-unter-UV-Licht.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-9-7446\" srcset=\"https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-unter-UV-Licht.jpg 1000w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-unter-UV-Licht-300x200.jpg 300w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-unter-UV-Licht-768x512.jpg 768w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-unter-UV-Licht-420x280.jpg 420w, https:\/\/www.madcham.de\/wp-content\/uploads\/2018\/06\/Brookesia-ambreense-unter-UV-Licht-81x54.jpg 81w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-9-7446'>\n\t\t\t\tDas gleiche Tier unter UV-Licht\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La premi\u00e8re chose que la plupart des gens pensent d&rsquo;un cam\u00e9l\u00e9on est g\u00e9n\u00e9ralement le fait que ces animaux peuvent changer la couleur de leur peau. Cet article va au fond de la question de savoir comment fonctionne ce changement de couleur et \u00e0 quoi il sert r\u00e9ellement. &nbsp; Comment fonctionne le changement de couleur du cam\u00e9l\u00e9on ? Les chromatophores, cellules optiques sp\u00e9cialis\u00e9es de la peau, sont responsables du changement de couleur. Ils sont situ\u00e9s sous la couche de peau la plus externe (\u00e9piderme) du derme, en couches superpos\u00e9es. Les m\u00e9lanophores sont responsables des couleurs bleu fonc\u00e9 et noir, les xanthophores des pigments jaunes et oranges, les \u00e9rythrophores des pigments rouges et les guanophores des pigments brillants argent\u00e9s. Chez les cam\u00e9l\u00e9ons, il y a aussi des cellules qui n&rsquo;ont pas du tout besoin de pigments pour que la peau apparaisse de couleur diff\u00e9rente. Ils effectuent le changement de couleur par r\u00e9flexion. Une distinction est faite entre une couche sup\u00e9rieure (en anglais superifical) d&rsquo;iridophores S et une couche inf\u00e9rieure (en anglais deep) d&rsquo;iridophores D. Les iridophores contiennent des cristaux de guanine, qui sont la cl\u00e9 du changement de couleur des cam\u00e9l\u00e9ons. Dans la couche sup\u00e9rieure des S-iridophores, les cristaux de guanine sont&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2546,42],"tags":[1627,1629,1630,1628,1624,1636,1623,1639,1632,1631,1626,1637,1633,1634,1554,1635,1640,1642,1625,1641,1549,1638],"_links":{"self":[{"href":"https:\/\/www.madcham.de\/fr\/wp-json\/wp\/v2\/posts\/7444"}],"collection":[{"href":"https:\/\/www.madcham.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madcham.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madcham.de\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madcham.de\/fr\/wp-json\/wp\/v2\/comments?post=7444"}],"version-history":[{"count":15,"href":"https:\/\/www.madcham.de\/fr\/wp-json\/wp\/v2\/posts\/7444\/revisions"}],"predecessor-version":[{"id":9387,"href":"https:\/\/www.madcham.de\/fr\/wp-json\/wp\/v2\/posts\/7444\/revisions\/9387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.madcham.de\/fr\/wp-json\/wp\/v2\/media\/2612"}],"wp:attachment":[{"href":"https:\/\/www.madcham.de\/fr\/wp-json\/wp\/v2\/media?parent=7444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madcham.de\/fr\/wp-json\/wp\/v2\/categories?post=7444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madcham.de\/fr\/wp-json\/wp\/v2\/tags?post=7444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}